{"id":21,"date":"2023-07-30T11:37:53","date_gmt":"2023-07-30T09:37:53","guid":{"rendered":"https:\/\/aetherische-oele.net\/WP\/?p=21"},"modified":"2023-08-29T18:12:45","modified_gmt":"2023-08-29T16:12:45","slug":"ester","status":"publish","type":"post","link":"https:\/\/aetherische-oele.net\/WP\/ester\/","title":{"rendered":"Ester"},"content":{"rendered":"<h2>Ester<\/h2>\n<p>Unter dem Namen Esther werden verschiedenste Terpenester in eine Gruppe gefasst. Auch hier werden Monoterpenester und Sesquiterpenester gleichzeitig gemeint. Da diese beiden Varianten aber zum Gro\u00dfteil die gleichen Eigenschaften haben, ist es nicht n\u00f6tig, sie differenziert zu beschreiben.<\/p>\n<p>Generell haben diese Ester einen fruchtigen und blumigen Duft.<\/p>\n<h3>Die k\u00f6rperliche Wirkung der Ester<\/h3>\n<p>Terpenester sind recht stabil, sie reagieren also kaum mit der Umwelt. Das f\u00fchrt dazu, dass sie besonders hautfreundlich sind und dass sie besonders vertr\u00e4glich sind. Ein hoher ist der Gehalt in einem \u00d6l bedeutet, dass diese \u00d6l besonders gut bei Hautproblemen, besonders zu Beginn, wirkt. Diese \u00d6le hemmen Entz\u00fcndungen und helfen gegen Pilzerkrankungen. Generell wirken sie entspannend sie haben eine regulierende Wirkung auf die Serotonin Produktion. Deshalb sind sie besonders gut, wenn man schlecht schlafen kann. Sie helfen aber auch gegen Schmerzen, besonders gegen chronische Schmerzen. Sie helfen bei nerv\u00f6sen Herzbeschwerden oder bei einem schwankenden Blutdruck. Stresshormone werden abgesenkt, so dass das Herz entlastet wird. Gleichzeitig wird das Herz-Kreislauf-System ausgeglichen.<\/p>\n<p>\u00c4therische \u00d6le mit einem hohen Estergehalt sind besonders wichtig in der <a href=\"https:\/\/aetherische-oele.net\/WP\/aetherische-oele-in-der-pflege-aromapflege\/\">Aromapflege<\/a> und in der Aromatherapie, denn sie haben eine entkrampfende und entz\u00fcndungshemmende Wirkung, sie gleichen aus und sie sind vor allem, da sie besonders vertr\u00e4glich sind fast \u00fcberall verwendbar.<\/p>\n<h3>Die psychische Wirkung\u00a0der Ester<\/h3>\n<p>Sie wirken sehr beruhigend und entspannend auf das zentrale Nervensystem. Das Wohlbefinden wird gesteigert, die Serotonin-Aussch\u00fcttung in unserem Gehirn wird reguliert. Vielleicht kennen Sie das Serotonin aus der Behandlung von depressiven Menschen. Es wird eingesetzt, damit die Menschen heiterer und gelassener werden. Auch das soziale zwischen den Menschen wird gest\u00e4rkt und man traut sich wieder mehr Umgang mit anderen Menschen zu.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Ester wirken stark harmonisierend, entspannend und entkrampfend. Und das sowohl f\u00fcr den K\u00f6rper und die Seele.\u00a0 Sie sind Mitglieder der so genannten Serotonind\u00fcfte, die die Harmonie und die Balance in uns wiederherstellen.<\/p>\n<p>Wenn Sie zu viel arbeiten und daher Ihre Seele aus dem Blick verlieren, kann die <a href=\"https:\/\/aetherische-oele.net\/WP\/kamille-roemisch-anthemis-nobilis-2\/\">r\u00f6mische Kamille<\/a> und der <a href=\"https:\/\/aetherische-oele.net\/WP\/muskatellersalbeioel-salvia-sclarea-l\/\">Muskatellersalbei<\/a> Ihnen dabei helfen, Stress wieder los zu werden. Gleiches gilt \u00fcbrigens auch f\u00fcr Kindern in der Trotzphase&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Erkennbar an den Endungen -yl und -at<\/strong><\/p>\n<p>Eignen sich besonders f\u00fcr chronische Schmerzen<\/p>\n<p>&nbsp;<\/p>\n<h3>Wirkung der Ester<\/h3>\n<p>Hautfreundlich, gegen Pilze wirkend, lindert nerv\u00f6ses Herzklopfen, \u00c4ngste, reguliert den Blutdruck, wirkt antidepressiv, krampfl\u00f6send, entz\u00fcndungshemmend<\/p>\n<p>&nbsp;<\/p>\n<h3>In welchen Pflanzen steckt besonders viel Ester?<\/h3>\n<p><strong>Geranyl-Acetat:<\/strong> Echter <a href=\"https:\/\/aetherische-oele.net\/WP\/lavendeloel-lavandula-angustifolia\/\">Lavendel<\/a> (Lavandula vera) (bis zu 33%), <a href=\"https:\/\/aetherische-oele.net\/WP\/palmarosa-cymbopogon-martini\/\">Palmarosa<\/a> (Cymbopogon martinii) (bis zu 20%), Zitronengras (Cymbopogon nardus) (bis zu 8%)<\/p>\n<p><strong>Linalyl-Acetat:<\/strong> Muskatellersalbei (Salvia sclarea) (74%), <a href=\"https:\/\/aetherische-oele.net\/WP\/petit-grain-citrus-aurantium\/\">Petit Grain<\/a> (50%), <a href=\"https:\/\/aetherische-oele.net\/WP\/bergamotteoel-citrus-bergamia\/\">Bergamotte<\/a> (Citrus bergamia) (bis zu 40%), Lavendel (Lavandula angustifolia) und <a href=\"https:\/\/aetherische-oele.net\/WP\/lavandin-lavandula-hybrida\/\">Lavandin<\/a> (bis zu 36%)<\/p>\n<p><strong>Bornyl-Acetat: <\/strong> Alant (Inula graveolens) (bis zu 50%), Sibirische Tanne (Abies sibirica) (bis zu 40%), Echte Baldrianwurzel (Valeriana officinalis) (bis zu 33%)<\/p>\n<p><strong>Phytyl-Acetat:<\/strong> Jasmin (bis zu 10%)<\/p>\n<p>&nbsp;<\/p>\n<h3>\u00d6le mit generell hohen Konzentrationen<\/h3>\n<p>Muskatellersalbei -80%,<br \/>\nr\u00f6mische Kamille -80%,<br \/>\nImmortelle -70%,<br \/>\nPetit grain Bitterorange -60%<br \/>\nLavendel &#8211; 50%,<br \/>\nBergamotteminze -50%,<br \/>\nBergamotte -45%,<br \/>\nLavandin -45%,<br \/>\n<a href=\"https:\/\/aetherische-oele.net\/WP\/kardamomoel-ellettaria-cardamomum\/\">Kardamom<\/a> -45%<br \/>\nLavandin -45%<br \/>\nFichte sibirisch -44%,<br \/>\nRosengeranium -30%<br \/>\n<a href=\"https:\/\/aetherische-oele.net\/WP\/nerolioel-citrus-bigaradia-und-aurantium\/\">Neroli<\/a> -18%<br \/>\n<a href=\"https:\/\/aetherische-oele.net\/WP\/thymianoel-thymus-vulgaris\/\">Thymian<\/a> ct. <a href=\"https:\/\/aetherische-oele.net\/WP\/linalool\/\">Linalool<\/a> -15%<br \/>\nPalmarosa -15%<br \/>\n<a href=\"https:\/\/aetherische-oele.net\/WP\/cistrose-cistus-ladanifer\/\">Cistrose<\/a> -15%<br \/>\n<a href=\"https:\/\/aetherische-oele.net\/WP\/weisstanne-abies-alba\/\">Wei\u00dftanne<\/a> -10%<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Quellen:<\/strong><\/p>\n\n<div data-post-id=\"2503\" class=\"insert-page insert-page-2503 \"><p><a href=\"https:\/\/aetherische-oele.net\/WP\/wp-content\/uploads\/41IFM6XF7IL._SX351_BO1204203200_1.jpg\"><img decoding=\"async\" class=\"size-thumbnail wp-image-2509 alignleft lazyload\" data-src=\"https:\/\/aetherische-oele.net\/WP\/wp-content\/uploads\/41IFM6XF7IL._SX351_BO1204203200_1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" data-srcset=\"https:\/\/aetherische-oele.net\/WP\/wp-content\/uploads\/\/41IFM6XF7IL._SX351_BO1204203200_1-150x150.jpg 150w, https:\/\/aetherische-oele.net\/WP\/wp-content\/uploads\/\/41IFM6XF7IL._SX351_BO1204203200_1-300x300.jpg 300w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\" \/><\/a><a href=\"https:\/\/amzn.to\/45LwEuG\">Praxis Aromatherapie &#8211; Haug-Verlag<\/a><\/p>\n<\/div>\n<p><code>  <script src=\"https:\/\/cdn.jsdelivr.net\/npm\/chart.js\"><\/script><\/p>\n<p><\/code><\/p>\n<h1>Doughnut Chart from Template<\/h1>\n<p>&nbsp;<\/p>\n<p><script>\n  \/\/ Ihre Datenvorlage als JavaScript-Objekt\n  const templateData = {\n    categories: ['Obst', 'Gem\u00fcse', 'Fleisch', 'Sonstiges'],\n    values: [40, 30, 20, 10]\n  };<\/p>\n<p>  \/\/ Daten und Konfiguration f\u00fcr das Doughnut-Diagramm\n  const data = {\n    labels: templateData.categories,\n    datasets: [{\n      data: templateData.values,\n      backgroundColor: [\n        'rgba(255, 99, 132, 0.5)',\n        'rgba(54, 162, 235, 0.5)',\n        'rgba(255, 206, 86, 0.5)',\n        'rgba(75, 192, 192, 0.5)'\n      ],\n      borderColor: [\n        'rgba(255, 99, 132, 1)',\n        'rgba(54, 162, 235, 1)',\n        'rgba(255, 206, 86, 1)',\n        'rgba(75, 192, 192, 1)'\n      ],\n      borderWidth: 1\n    }]\n  };<\/p>\n<p>  \/\/ Diagramm erstellen\n  const ctx = document.getElementById('myDoughnutChart').getContext('2d');\n  const myDoughnutChart = new Chart(ctx, {\n    type: 'doughnut',\n    data: data\n  });\n<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ester Unter dem Namen Esther werden verschiedenste Terpenester in eine Gruppe gefasst. Auch hier werden Monoterpenester und Sesquiterpenester gleichzeitig gemeint. Da diese beiden Varianten aber zum Gro\u00dfteil die gleichen Eigenschaften haben, ist es nicht n\u00f6tig, sie differenziert zu beschreiben. Generell haben diese Ester einen fruchtigen und blumigen Duft. Die k\u00f6rperliche Wirkung der Ester Terpenester sind [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_metis_text_type":"standard","_metis_text_length":3751,"_post_count":0,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-21","post","type-post","status-publish","format-standard","hentry","category-inhaltsstoffe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ester - Aromatherapie - Aromapflege - \u00c4therische \u00d6le<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aetherische-oele.net\/WP\/ester\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ester - Aromatherapie - Aromapflege - \u00c4therische \u00d6le\" \/>\n<meta property=\"og:description\" content=\"Ester Unter dem Namen Esther werden verschiedenste Terpenester in eine Gruppe gefasst. Auch hier werden Monoterpenester und Sesquiterpenester gleichzeitig gemeint. Da diese beiden Varianten aber zum Gro\u00dfteil die gleichen Eigenschaften haben, ist es nicht n\u00f6tig, sie differenziert zu beschreiben. Generell haben diese Ester einen fruchtigen und blumigen Duft. Die k\u00f6rperliche Wirkung der Ester Terpenester sind [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aetherische-oele.net\/WP\/ester\/\" \/>\n<meta property=\"og:site_name\" content=\"Aromatherapie - Aromapflege - \u00c4therische \u00d6le\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-30T09:37:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-29T16:12:45+00:00\" \/>\n<meta name=\"author\" content=\"Baumann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Baumann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/ester\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/ester\\\/\"},\"author\":{\"name\":\"Baumann\",\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/#\\\/schema\\\/person\\\/718436a4d57be3f5f8a8b75c925b3ee3\"},\"headline\":\"Ester\",\"datePublished\":\"2023-07-30T09:37:53+00:00\",\"dateModified\":\"2023-08-29T16:12:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/ester\\\/\"},\"wordCount\":530,\"commentCount\":0,\"articleSection\":[\"Inhaltsstoffe\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/ester\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/ester\\\/\",\"url\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/ester\\\/\",\"name\":\"Ester - Aromatherapie - Aromapflege - \u00c4therische \u00d6le\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/#website\"},\"datePublished\":\"2023-07-30T09:37:53+00:00\",\"dateModified\":\"2023-08-29T16:12:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/#\\\/schema\\\/person\\\/718436a4d57be3f5f8a8b75c925b3ee3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/ester\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/ester\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/ester\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ester\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/#website\",\"url\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/\",\"name\":\"Aromatherapie - Aromapflege - \u00c4therische \u00d6le\",\"description\":\"Das Kompendium online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/#\\\/schema\\\/person\\\/718436a4d57be3f5f8a8b75c925b3ee3\",\"name\":\"Baumann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9abffec4357dcdde45f860e431c87387eaefedc4e2fdb4985ebe40a0500b7e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9abffec4357dcdde45f860e431c87387eaefedc4e2fdb4985ebe40a0500b7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9abffec4357dcdde45f860e431c87387eaefedc4e2fdb4985ebe40a0500b7e?s=96&d=mm&r=g\",\"caption\":\"Baumann\"},\"sameAs\":[\"https:\\\/\\\/aetherische-oele.net\\\/WP\"],\"url\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/author\\\/baumann\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ester - Aromatherapie - Aromapflege - \u00c4therische \u00d6le","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aetherische-oele.net\/WP\/ester\/","og_locale":"de_DE","og_type":"article","og_title":"Ester - Aromatherapie - Aromapflege - \u00c4therische \u00d6le","og_description":"Ester Unter dem Namen Esther werden verschiedenste Terpenester in eine Gruppe gefasst. Auch hier werden Monoterpenester und Sesquiterpenester gleichzeitig gemeint. Da diese beiden Varianten aber zum Gro\u00dfteil die gleichen Eigenschaften haben, ist es nicht n\u00f6tig, sie differenziert zu beschreiben. Generell haben diese Ester einen fruchtigen und blumigen Duft. Die k\u00f6rperliche Wirkung der Ester Terpenester sind [&hellip;]","og_url":"https:\/\/aetherische-oele.net\/WP\/ester\/","og_site_name":"Aromatherapie - Aromapflege - \u00c4therische \u00d6le","article_published_time":"2023-07-30T09:37:53+00:00","article_modified_time":"2023-08-29T16:12:45+00:00","author":"Baumann","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Baumann","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aetherische-oele.net\/WP\/ester\/#article","isPartOf":{"@id":"https:\/\/aetherische-oele.net\/WP\/ester\/"},"author":{"name":"Baumann","@id":"https:\/\/aetherische-oele.net\/WP\/#\/schema\/person\/718436a4d57be3f5f8a8b75c925b3ee3"},"headline":"Ester","datePublished":"2023-07-30T09:37:53+00:00","dateModified":"2023-08-29T16:12:45+00:00","mainEntityOfPage":{"@id":"https:\/\/aetherische-oele.net\/WP\/ester\/"},"wordCount":530,"commentCount":0,"articleSection":["Inhaltsstoffe"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/aetherische-oele.net\/WP\/ester\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/aetherische-oele.net\/WP\/ester\/","url":"https:\/\/aetherische-oele.net\/WP\/ester\/","name":"Ester - Aromatherapie - Aromapflege - \u00c4therische \u00d6le","isPartOf":{"@id":"https:\/\/aetherische-oele.net\/WP\/#website"},"datePublished":"2023-07-30T09:37:53+00:00","dateModified":"2023-08-29T16:12:45+00:00","author":{"@id":"https:\/\/aetherische-oele.net\/WP\/#\/schema\/person\/718436a4d57be3f5f8a8b75c925b3ee3"},"breadcrumb":{"@id":"https:\/\/aetherische-oele.net\/WP\/ester\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aetherische-oele.net\/WP\/ester\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aetherische-oele.net\/WP\/ester\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/aetherische-oele.net\/WP\/"},{"@type":"ListItem","position":2,"name":"Ester"}]},{"@type":"WebSite","@id":"https:\/\/aetherische-oele.net\/WP\/#website","url":"https:\/\/aetherische-oele.net\/WP\/","name":"Aromatherapie - Aromapflege - \u00c4therische \u00d6le","description":"Das Kompendium online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aetherische-oele.net\/WP\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/aetherische-oele.net\/WP\/#\/schema\/person\/718436a4d57be3f5f8a8b75c925b3ee3","name":"Baumann","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5d9abffec4357dcdde45f860e431c87387eaefedc4e2fdb4985ebe40a0500b7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d9abffec4357dcdde45f860e431c87387eaefedc4e2fdb4985ebe40a0500b7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d9abffec4357dcdde45f860e431c87387eaefedc4e2fdb4985ebe40a0500b7e?s=96&d=mm&r=g","caption":"Baumann"},"sameAs":["https:\/\/aetherische-oele.net\/WP"],"url":"https:\/\/aetherische-oele.net\/WP\/author\/baumann\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","public_identification_id":"a7d3967987e14e8f90f89b1218532a5e","private_identification_id":"966bc2a4e1504c559f30cf23569dd60d","_links":{"self":[{"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/posts\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/comments?post=21"}],"version-history":[{"count":6,"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/posts\/21\/revisions"}],"predecessor-version":[{"id":788,"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/posts\/21\/revisions\/788"}],"wp:attachment":[{"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/media?parent=21"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/categories?post=21"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/tags?post=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}