{"id":3858,"date":"2025-05-29T09:59:44","date_gmt":"2025-05-29T07:59:44","guid":{"rendered":"https:\/\/aetherische-oele.net\/WP\/?p=3858"},"modified":"2025-05-29T10:00:18","modified_gmt":"2025-05-29T08:00:18","slug":"3858-2","status":"publish","type":"post","link":"https:\/\/aetherische-oele.net\/WP\/3858-2\/","title":{"rendered":"Die Zyklusphasen der Frauen und Aromatherapie"},"content":{"rendered":"<blockquote class=\"wp-embedded-content\" data-secret=\"bezGli6s1b\"><p><a href=\"https:\/\/aetherische-oele.net\/WP\/die-zyklusphasen-der-frau-und-aromatherapie\/\">Die Zyklusphasen der Frau und Aromatherapie<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content lazyload\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8222;Die Zyklusphasen der Frau und Aromatherapie&#8220; &#8212; Aromatherapie - Aromapflege - \u00c4therische \u00d6le\" data-src=\"https:\/\/aetherische-oele.net\/WP\/die-zyklusphasen-der-frau-und-aromatherapie\/embed\/#?secret=gufo2DZ3dc#?secret=bezGli6s1b\" data-secret=\"bezGli6s1b\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-load-mode=\"1\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Zyklusphasen der Frau und Aromatherapie<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_metis_text_type":"standard","_metis_text_length":43,"_post_count":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3858","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Zyklusphasen der Frauen und Aromatherapie - Aromatherapie - Aromapflege - \u00c4therische \u00d6le<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aetherische-oele.net\/WP\/3858-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Zyklusphasen der Frauen und Aromatherapie - Aromatherapie - Aromapflege - \u00c4therische \u00d6le\" \/>\n<meta property=\"og:description\" content=\"Die Zyklusphasen der Frau und Aromatherapie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aetherische-oele.net\/WP\/3858-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Aromatherapie - Aromapflege - \u00c4therische \u00d6le\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-29T07:59:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-29T08:00:18+00:00\" \/>\n<meta name=\"author\" content=\"Baumann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Baumann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/3858-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/3858-2\\\/\"},\"author\":{\"name\":\"Baumann\",\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/#\\\/schema\\\/person\\\/718436a4d57be3f5f8a8b75c925b3ee3\"},\"headline\":\"Die Zyklusphasen der Frauen und Aromatherapie\",\"datePublished\":\"2025-05-29T07:59:44+00:00\",\"dateModified\":\"2025-05-29T08:00:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/3858-2\\\/\"},\"wordCount\":11,\"commentCount\":0,\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/3858-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/3858-2\\\/\",\"url\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/3858-2\\\/\",\"name\":\"Die Zyklusphasen der Frauen und Aromatherapie - Aromatherapie - Aromapflege - \u00c4therische \u00d6le\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/#website\"},\"datePublished\":\"2025-05-29T07:59:44+00:00\",\"dateModified\":\"2025-05-29T08:00:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/#\\\/schema\\\/person\\\/718436a4d57be3f5f8a8b75c925b3ee3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/3858-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/3858-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/3858-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Zyklusphasen der Frauen und Aromatherapie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/#website\",\"url\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/\",\"name\":\"Aromatherapie - Aromapflege - \u00c4therische \u00d6le\",\"description\":\"Das Kompendium online\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/#\\\/schema\\\/person\\\/718436a4d57be3f5f8a8b75c925b3ee3\",\"name\":\"Baumann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9abffec4357dcdde45f860e431c87387eaefedc4e2fdb4985ebe40a0500b7e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9abffec4357dcdde45f860e431c87387eaefedc4e2fdb4985ebe40a0500b7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5d9abffec4357dcdde45f860e431c87387eaefedc4e2fdb4985ebe40a0500b7e?s=96&d=mm&r=g\",\"caption\":\"Baumann\"},\"sameAs\":[\"https:\\\/\\\/aetherische-oele.net\\\/WP\"],\"url\":\"https:\\\/\\\/aetherische-oele.net\\\/WP\\\/author\\\/baumann\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Zyklusphasen der Frauen und Aromatherapie - Aromatherapie - Aromapflege - \u00c4therische \u00d6le","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aetherische-oele.net\/WP\/3858-2\/","og_locale":"de_DE","og_type":"article","og_title":"Die Zyklusphasen der Frauen und Aromatherapie - Aromatherapie - Aromapflege - \u00c4therische \u00d6le","og_description":"Die Zyklusphasen der Frau und Aromatherapie","og_url":"https:\/\/aetherische-oele.net\/WP\/3858-2\/","og_site_name":"Aromatherapie - Aromapflege - \u00c4therische \u00d6le","article_published_time":"2025-05-29T07:59:44+00:00","article_modified_time":"2025-05-29T08:00:18+00:00","author":"Baumann","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Baumann","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aetherische-oele.net\/WP\/3858-2\/#article","isPartOf":{"@id":"https:\/\/aetherische-oele.net\/WP\/3858-2\/"},"author":{"name":"Baumann","@id":"https:\/\/aetherische-oele.net\/WP\/#\/schema\/person\/718436a4d57be3f5f8a8b75c925b3ee3"},"headline":"Die Zyklusphasen der Frauen und Aromatherapie","datePublished":"2025-05-29T07:59:44+00:00","dateModified":"2025-05-29T08:00:18+00:00","mainEntityOfPage":{"@id":"https:\/\/aetherische-oele.net\/WP\/3858-2\/"},"wordCount":11,"commentCount":0,"articleSection":["Uncategorized"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/aetherische-oele.net\/WP\/3858-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/aetherische-oele.net\/WP\/3858-2\/","url":"https:\/\/aetherische-oele.net\/WP\/3858-2\/","name":"Die Zyklusphasen der Frauen und Aromatherapie - Aromatherapie - Aromapflege - \u00c4therische \u00d6le","isPartOf":{"@id":"https:\/\/aetherische-oele.net\/WP\/#website"},"datePublished":"2025-05-29T07:59:44+00:00","dateModified":"2025-05-29T08:00:18+00:00","author":{"@id":"https:\/\/aetherische-oele.net\/WP\/#\/schema\/person\/718436a4d57be3f5f8a8b75c925b3ee3"},"breadcrumb":{"@id":"https:\/\/aetherische-oele.net\/WP\/3858-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aetherische-oele.net\/WP\/3858-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aetherische-oele.net\/WP\/3858-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/aetherische-oele.net\/WP\/"},{"@type":"ListItem","position":2,"name":"Die Zyklusphasen der Frauen und Aromatherapie"}]},{"@type":"WebSite","@id":"https:\/\/aetherische-oele.net\/WP\/#website","url":"https:\/\/aetherische-oele.net\/WP\/","name":"Aromatherapie - Aromapflege - \u00c4therische \u00d6le","description":"Das Kompendium online","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aetherische-oele.net\/WP\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/aetherische-oele.net\/WP\/#\/schema\/person\/718436a4d57be3f5f8a8b75c925b3ee3","name":"Baumann","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5d9abffec4357dcdde45f860e431c87387eaefedc4e2fdb4985ebe40a0500b7e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5d9abffec4357dcdde45f860e431c87387eaefedc4e2fdb4985ebe40a0500b7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5d9abffec4357dcdde45f860e431c87387eaefedc4e2fdb4985ebe40a0500b7e?s=96&d=mm&r=g","caption":"Baumann"},"sameAs":["https:\/\/aetherische-oele.net\/WP"],"url":"https:\/\/aetherische-oele.net\/WP\/author\/baumann\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"public_identification_id":"6026aa30e71c49999e8f8c9a0f5ce955","private_identification_id":"15802c2e6e5e4362b4e90847dc85416d","_links":{"self":[{"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/posts\/3858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/comments?post=3858"}],"version-history":[{"count":3,"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/posts\/3858\/revisions"}],"predecessor-version":[{"id":3862,"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/posts\/3858\/revisions\/3862"}],"wp:attachment":[{"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/media?parent=3858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/categories?post=3858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aetherische-oele.net\/WP\/wp-json\/wp\/v2\/tags?post=3858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}